{"id":3550,"date":"2026-09-01T12:00:46","date_gmt":"2026-09-01T12:00:46","guid":{"rendered":"https:\/\/sanad.webbingstone.org\/success-stories\/azza\/"},"modified":"2026-09-01T12:08:29","modified_gmt":"2026-09-01T12:08:29","slug":"azza","status":"publish","type":"success-stories","link":"https:\/\/sanadorphans.org\/ar\/success-stories\/azza\/","title":{"rendered":"Azza"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/sanadorphans.org\/storage\/stories\/August2024\/tu5RhLKVsL66YgVLk7PJ.jpg\" alt=\"Azza\"\/><\/figure>\n","protected":false},"featured_media":3585,"template":"","class_list":["post-3550","success-stories","type-success-stories","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/sanadorphans.org\/ar\/wp-json\/wp\/v2\/success-stories\/3550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanadorphans.org\/ar\/wp-json\/wp\/v2\/success-stories"}],"about":[{"href":"https:\/\/sanadorphans.org\/ar\/wp-json\/wp\/v2\/types\/success-stories"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanadorphans.org\/ar\/wp-json\/wp\/v2\/media\/3585"}],"wp:attachment":[{"href":"https:\/\/sanadorphans.org\/ar\/wp-json\/wp\/v2\/media?parent=3550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}